{"id":5111,"date":"2025-01-18T23:11:30","date_gmt":"2025-01-18T22:11:30","guid":{"rendered":"https:\/\/dianadelajara.com\/criadero-de-perros-sant-boi-de-llobregat\/"},"modified":"2025-01-18T23:11:30","modified_gmt":"2025-01-18T22:11:30","slug":"criadero-de-perros-sant-boi-de-llobregat","status":"publish","type":"post","link":"https:\/\/dianadelajara.com\/en\/city\/dog-kennel-sant-boi-de-llobregat\/","title":{"rendered":"Sant Boi de Llobregat Dog Kennel\u00a0"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Diana de la Jara offers a kennel in Sant Boi de Llobregat with decades of commitment to responsible breeding. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">We have a wide variety of puppies of different breeds, all of them with their veterinary card updated and raised in a cheerful, safe and spacious environment.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Zoological core<\/em>: <strong>GR105<\/strong><\/p>\n\n\n<div class=\"gb-container gb-container-638fc618\">\n\n<a class=\"gb-button gb-button-9c254db8\" href=\"tel:+34601632807\"><span class=\"gb-icon\"><svg aria-hidden=\"true\" role=\"img\" height=\"1em\" width=\"1em\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path fill=\"currentColor\" d=\"M493.4 24.6l-104-24c-11.3-2.6-22.9 3.3-27.5 13.9l-48 112c-4.2 9.8-1.4 21.3 6.9 28l60.6 49.6c-36 76.7-98.9 140.5-177.2 177.2l-49.6-60.6c-6.8-8.3-18.2-11.1-28-6.9l-112 48C3.9 366.5-2 378.1.6 389.4l24 104C27.1 504.2 36.7 512 48 512c256.1 0 464-207.5 464-464 0-11.2-7.7-20.9-18.6-23.4z\"><\/path><\/svg><\/span><span class=\"gb-button-text\">CALL NOW<\/span><\/a>\n\n\n\n<div style=\"height:39px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"gb-headline gb-headline-039864c6\"><span class=\"gb-icon\"><svg aria-hidden=\"true\" role=\"img\" height=\"1em\" width=\"1em\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path fill=\"currentColor\" d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg><\/span><span class=\"gb-headline-text\">We give you an instant price<\/span><\/p>\n\n<\/div>\n\n\n<h2 class=\"wp-block-heading\">Your Trusted Dog Breeder in Sant Boi de Llobregat<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">If you are looking in Sant Boi de Llobregat, trust Diana de la Jara as your reliable kennel. With a solid track record of more than 25 years, we breed puppies with love and professionalism. We strive to ensure that every puppy is healthy and happy.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Breeds<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li>\u2705&nbsp;<a href=\"https:\/\/dianadelajara.com\/en\/breeder\/pomeranian-kennel\/\" data-type=\"page\" data-id=\"4608\">Pomeranian<\/a><\/li>\n\n\n\n<li>\u2705&nbsp;<a href=\"https:\/\/dianadelajara.com\/en\/breeder\/bichon-maltese-kennel\/\" data-type=\"post\" data-id=\"4677\">Maltese Bichon<\/a><\/li>\n\n\n\n<li>\u2705&nbsp;<a href=\"https:\/\/dianadelajara.com\/en\/breeder\/yorkshire-kennel\/\" data-type=\"post\" data-id=\"4679\">Yorkshire<\/a><\/li>\n\n\n\n<li>\u2705&nbsp;<a href=\"https:\/\/dianadelajara.com\/en\/breeder\/toy-poodle-cattery\/\" data-type=\"post\" data-id=\"4681\">Toy Poodle<\/a><\/li>\n\n\n\n<li>\u2705&nbsp;<a href=\"https:\/\/dianadelajara.com\/en\/breeder\/chihuahua-kennel\/\" data-type=\"post\" data-id=\"4683\">Chihuahua<\/a><\/li>\n\n\n\n<li>\u2705&nbsp;<a href=\"https:\/\/dianadelajara.com\/en\/breeder\/westy-kennel\/\" data-type=\"post\" data-id=\"4685\">Westy<\/a><\/li>\n\n\n\n<li>\u2705&nbsp;<a href=\"https:\/\/dianadelajara.com\/en\/breeder\/beagle-kennel\/\" data-type=\"post\" data-id=\"4687\">Beagle<\/a><\/li>\n\n\n\n<li>\u2705&nbsp;<a href=\"https:\/\/dianadelajara.com\/en\/breeder\/shih-tzu-kennel\/\" data-type=\"post\" data-id=\"4689\">Shih Tzu<\/a><\/li>\n\n\n\n<li>\u2705&nbsp;<a href=\"https:\/\/dianadelajara.com\/en\/breeder\/maltipoo-hatchery\/\" data-type=\"post\" data-id=\"4691\">Maltipoo<\/a><\/li>\n\n\n\n<li>\u2705&nbsp;<a href=\"https:\/\/dianadelajara.com\/en\/breeder\/french-bulldog-kennel\/\" data-type=\"post\" data-id=\"4693\">French Bulldog<\/a><\/li>\n\n\n\n<li>\u2705&nbsp;<a href=\"https:\/\/dianadelajara.com\/en\/breeder\/dachshund-kennel\/\" data-type=\"post\" data-id=\"4695\">Dachshund<\/a><\/li>\n\n\n\n<li>\u2705&nbsp;<a href=\"https:\/\/dianadelajara.com\/en\/breeder\/biewer-hatchery\/\" data-type=\"post\" data-id=\"4696\">Biewer<\/a><\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Looking for puppies in Sant Boi de Llobregat? Diana de la Jara is your place<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">At Diana de la Jara we specialise in breeding lovely puppies with excellent genetics of breeds such as Bichon Maltese, Yorkshire, Toy Poodle, Pomeranian, Westy, Beagle, Chihuahua, Sitzu, Maltipoo, French Bulldog, Teckel and Biewer.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">What drives us is to offer you not just a puppy, but a healthy and happy member of your household.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img decoding=\"async\" width=\"599\" height=\"305\" src=\"https:\/\/dianadelajara.com\/wp-content\/uploads\/2025\/01\/cachorros-criadero-canino-diana-de-la-jara-1.jpg\" alt=\"puppies-puppies-breeder-canine-diana-de-la-jara\" class=\"wp-image-4949\" srcset=\"https:\/\/dianadelajara.com\/wp-content\/uploads\/2025\/01\/cachorros-criadero-canino-diana-de-la-jara-1.jpg 599w, https:\/\/dianadelajara.com\/wp-content\/uploads\/2025\/01\/cachorros-criadero-canino-diana-de-la-jara-1-300x153.jpg 300w, https:\/\/dianadelajara.com\/wp-content\/uploads\/2025\/01\/cachorros-criadero-canino-diana-de-la-jara-1-18x9.jpg 18w\" sizes=\"(max-width: 599px) 100vw, 599px\" \/><\/figure>\n<\/div>\n\n\n<h3 class=\"wp-block-heading\">Commitment to the Health and Welfare of Our Puppies<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Each of our puppies is treated with specialised and loving care, including regular health checks, daily interaction for their development, extreme care in cleanliness and well-being and healthy food adapted to their growth.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">We send puppies to any part of the country<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Regardless of your location, we bring your new puppy directly to your home anywhere in Spain, both on the peninsula, Balearic Islands and more. With our guaranteed delivery method, distance is no longer an obstacle.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Contact with us<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Ready to welcome your new puppy? Call or email us! Our team of dog breeding experts is ready to advise you and offer you all the information you need.<\/p>\n\n\n<div class=\"gb-container gb-container-f669a2c1 gbp-card--border\">\n<div class=\"gb-container gb-container-edfffa11\">\n\n<h3 class=\"gb-headline gb-headline-8a8bfa5a gb-headline-text\">Do you want to buy a puppy in Sant Boi de Llobregat with guarantees?<\/h3>\n\n\n\n<div class=\"gb-headline gb-headline-15e9eaff gb-headline-text\">Contact the best professionals in dog breeding.<\/div>\n\n\n<div class=\"gb-container gb-container-f97c5054\">\n\n<a class=\"gb-button gb-button-7185ef94 gb-button-text gbp-button--primary\" href=\"https:\/\/dianadelajara.com\/en\/contact\/\">Contact<\/a>\n\n\n\n<ul class=\"wp-block-social-links is-layout-flex wp-block-social-links-is-layout-flex\"><li class=\"wp-social-link wp-social-link-whatsapp wp-block-social-link\"><a href=\"https:\/\/wa.me\/34601632807\" class=\"wp-block-social-link-anchor\" rel=\"nofollow noopener\" target=\"_blank\"><svg width=\"24\" height=\"24\" viewbox=\"0 0 24 24\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" aria-hidden=\"true\" focusable=\"false\"><path d=\"M 12.011719 2 C 6.5057187 2 2.0234844 6.478375 2.0214844 11.984375 C 2.0204844 13.744375 2.4814687 15.462563 3.3554688 16.976562 L 2 22 L 7.2324219 20.763672 C 8.6914219 21.559672 10.333859 21.977516 12.005859 21.978516 L 12.009766 21.978516 C 17.514766 21.978516 21.995047 17.499141 21.998047 11.994141 C 22.000047 9.3251406 20.962172 6.8157344 19.076172 4.9277344 C 17.190172 3.0407344 14.683719 2.001 12.011719 2 z M 12.009766 4 C 14.145766 4.001 16.153109 4.8337969 17.662109 6.3417969 C 19.171109 7.8517969 20.000047 9.8581875 19.998047 11.992188 C 19.996047 16.396187 16.413812 19.978516 12.007812 19.978516 C 10.674812 19.977516 9.3544062 19.642812 8.1914062 19.007812 L 7.5175781 18.640625 L 6.7734375 18.816406 L 4.8046875 19.28125 L 5.2851562 17.496094 L 5.5019531 16.695312 L 5.0878906 15.976562 C 4.3898906 14.768562 4.0204844 13.387375 4.0214844 11.984375 C 4.0234844 7.582375 7.6067656 4 12.009766 4 z M 8.4765625 7.375 C 8.3095625 7.375 8.0395469 7.4375 7.8105469 7.6875 C 7.5815469 7.9365 6.9355469 8.5395781 6.9355469 9.7675781 C 6.9355469 10.995578 7.8300781 12.182609 7.9550781 12.349609 C 8.0790781 12.515609 9.68175 15.115234 12.21875 16.115234 C 14.32675 16.946234 14.754891 16.782234 15.212891 16.740234 C 15.670891 16.699234 16.690438 16.137687 16.898438 15.554688 C 17.106437 14.971687 17.106922 14.470187 17.044922 14.367188 C 16.982922 14.263188 16.816406 14.201172 16.566406 14.076172 C 16.317406 13.951172 15.090328 13.348625 14.861328 13.265625 C 14.632328 13.182625 14.464828 13.140625 14.298828 13.390625 C 14.132828 13.640625 13.655766 14.201187 13.509766 14.367188 C 13.363766 14.534188 13.21875 14.556641 12.96875 14.431641 C 12.71875 14.305641 11.914938 14.041406 10.960938 13.191406 C 10.218937 12.530406 9.7182656 11.714844 9.5722656 11.464844 C 9.4272656 11.215844 9.5585938 11.079078 9.6835938 10.955078 C 9.7955938 10.843078 9.9316406 10.663578 10.056641 10.517578 C 10.180641 10.371578 10.223641 10.267562 10.306641 10.101562 C 10.389641 9.9355625 10.347156 9.7890625 10.285156 9.6640625 C 10.223156 9.5390625 9.737625 8.3065 9.515625 7.8125 C 9.328625 7.3975 9.131125 7.3878594 8.953125 7.3808594 C 8.808125 7.3748594 8.6425625 7.375 8.4765625 7.375 z\"><\/path><\/svg><span class=\"wp-block-social-link-label screen-reader-text\">WhatsApp<\/span><\/a><\/li><\/ul>\n\n\n\n<ul class=\"wp-block-social-links is-layout-flex wp-block-social-links-is-layout-flex\"><li class=\"wp-social-link wp-social-link-instagram wp-block-social-link\"><a href=\"https:\/\/www.instagram.com\/familia_diana_de_la_jara\" class=\"wp-block-social-link-anchor\" rel=\"nofollow noopener\" target=\"_blank\"><svg width=\"24\" height=\"24\" viewbox=\"0 0 24 24\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" aria-hidden=\"true\" focusable=\"false\"><path d=\"M12,4.622c2.403,0,2.688,0.009,3.637,0.052c0.877,0.04,1.354,0.187,1.671,0.31c0.42,0.163,0.72,0.358,1.035,0.673 c0.315,0.315,0.51,0.615,0.673,1.035c0.123,0.317,0.27,0.794,0.31,1.671c0.043,0.949,0.052,1.234,0.052,3.637 s-0.009,2.688-0.052,3.637c-0.04,0.877-0.187,1.354-0.31,1.671c-0.163,0.42-0.358,0.72-0.673,1.035 c-0.315,0.315-0.615,0.51-1.035,0.673c-0.317,0.123-0.794,0.27-1.671,0.31c-0.949,0.043-1.233,0.052-3.637,0.052 s-2.688-0.009-3.637-0.052c-0.877-0.04-1.354-0.187-1.671-0.31c-0.42-0.163-0.72-0.358-1.035-0.673 c-0.315-0.315-0.51-0.615-0.673-1.035c-0.123-0.317-0.27-0.794-0.31-1.671C4.631,14.688,4.622,14.403,4.622,12 s0.009-2.688,0.052-3.637c0.04-0.877,0.187-1.354,0.31-1.671c0.163-0.42,0.358-0.72,0.673-1.035 c0.315-0.315,0.615-0.51,1.035-0.673c0.317-0.123,0.794-0.27,1.671-0.31C9.312,4.631,9.597,4.622,12,4.622 M12,3 C9.556,3,9.249,3.01,8.289,3.054C7.331,3.098,6.677,3.25,6.105,3.472C5.513,3.702,5.011,4.01,4.511,4.511 c-0.5,0.5-0.808,1.002-1.038,1.594C3.25,6.677,3.098,7.331,3.054,8.289C3.01,9.249,3,9.556,3,12c0,2.444,0.01,2.751,0.054,3.711 c0.044,0.958,0.196,1.612,0.418,2.185c0.23,0.592,0.538,1.094,1.038,1.594c0.5,0.5,1.002,0.808,1.594,1.038 c0.572,0.222,1.227,0.375,2.185,0.418C9.249,20.99,9.556,21,12,21s2.751-0.01,3.711-0.054c0.958-0.044,1.612-0.196,2.185-0.418 c0.592-0.23,1.094-0.538,1.594-1.038c0.5-0.5,0.808-1.002,1.038-1.594c0.222-0.572,0.375-1.227,0.418-2.185 C20.99,14.751,21,14.444,21,12s-0.01-2.751-0.054-3.711c-0.044-0.958-0.196-1.612-0.418-2.185c-0.23-0.592-0.538-1.094-1.038-1.594 c-0.5-0.5-1.002-0.808-1.594-1.038c-0.572-0.222-1.227-0.375-2.185-0.418C14.751,3.01,14.444,3,12,3L12,3z M12,7.378 c-2.552,0-4.622,2.069-4.622,4.622S9.448,16.622,12,16.622s4.622-2.069,4.622-4.622S14.552,7.378,12,7.378z M12,15 c-1.657,0-3-1.343-3-3s1.343-3,3-3s3,1.343,3,3S13.657,15,12,15z M16.804,6.116c-0.596,0-1.08,0.484-1.08,1.08 s0.484,1.08,1.08,1.08c0.596,0,1.08-0.484,1.08-1.08S17.401,6.116,16.804,6.116z\"><\/path><\/svg><span class=\"wp-block-social-link-label screen-reader-text\">Instagram<\/span><\/a><\/li><\/ul>\n\n<\/div>\n<\/div>\n\n<div class=\"gb-container gb-container-d8035122\">\n\n<figure class=\"gb-block-image gb-block-image-c5c9203a\"><img decoding=\"async\" width=\"600\" height=\"800\" class=\"gb-image gb-image-c5c9203a\" src=\"https:\/\/dianadelajara.com\/wp-content\/uploads\/2024\/11\/maltipoo-cachorro-diana-de-la-jara-2.jpg\" alt=\"maltipoo puppy - diana de la jara 2\" title=\"maltipoo puppy - diana de la jara 2\" srcset=\"https:\/\/dianadelajara.com\/wp-content\/uploads\/2024\/11\/maltipoo-cachorro-diana-de-la-jara-2.jpg 600w, https:\/\/dianadelajara.com\/wp-content\/uploads\/2024\/11\/maltipoo-cachorro-diana-de-la-jara-2-225x300.jpg 225w, https:\/\/dianadelajara.com\/wp-content\/uploads\/2024\/11\/maltipoo-cachorro-diana-de-la-jara-2-9x12.jpg 9w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure>\n\n<\/div>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Contact us and find out how to get your ideal puppy<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Don't wait any longer to expand your family! You can call us at <strong>601632807<\/strong> or contact us through our website and we will assist you in the selection of your new puppy.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">We guarantee compliance with the Animal Welfare Act and ensure that your new companion will arrive at your home in optimal conditions to adapt.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Choose from a wide variety of breeds<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">We have a diverse range of breeds for you to choose the puppy that fits perfectly into your life. All of our breeds have unique personalities, and we are sure you will find a loyal companion for you and your family.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Don't think twice! Diana de la Jara is the best option to find quality puppies in Sant Boi de Llobregat.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Commitment to Quality and After-sales Follow-up<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">We accompany you beyond the sale. We offer first-class after-sales care with veterinary care experts to ensure that your puppy adapts well to its new home and maintains a healthy and happy life.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Customer reviews of Diana de la Jara<\/h2>\n\n\n<pre class=\"ti-widget\" style=\"display: none\"><template id=\"trustindex-google-widget-html\"><div class=\"ti-widget  ti-goog ti-review-text-mode-readmore ti-text-align-left\" data-no-translation=\"true\" data-plugin-version=\"13.3.2\" data-layout-id=\"5\" data-layout-category=\"slider\" data-set-id=\"ligth-border\" data-pid=\"\" data-language=\"es\" data-close-locale=\"Cerca\" data-review-target-width=\"275\" data-css-version=\"2\" data-reply-by-locale=\"Respuesta del propietario\" data-only-rating-locale=\"Este usuario solo dej\u00f3 una calificaci\u00f3n.\" data-pager-autoplay-timeout=\"6\"> <div class=\"ti-widget-container ti-col-4\"> <div class=\"ti-footer ti-footer-grid source-Google\"> <div class=\"ti-fade-container\"> <div class=\"ti-rating-text\"> <strong class=\"ti-rating ti-rating-large\"> EXCELENTE <\/strong> <\/div> <span class=\"ti-stars star-lg\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 1\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 2\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 3\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 4\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/h.svg\" alt=\"Google star 5.0.6\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><\/span> <div class=\"ti-rating-text\"> <span class=\"nowrap\">A base de <strong>116 rese\u00f1as<\/strong><\/span> <\/div> <div class=\"ti-large-logo\"> <div class=\"ti-v-center\"> <trustindex-image class=\"ti-logo-fb\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/logo.svg\" width=\"150\" height=\"25\" loading=\"lazy\" alt=\"Google\"><\/trustindex-image> <\/div> <\/div> <\/div> <\/div> <div class=\"ti-reviews-container\"> <div class=\"ti-controls\"> <div class=\"ti-next\" aria-label=\"Siguiente rese\u00f1a\" role=\"button\" tabindex=\"0\"><\/div> <div class=\"ti-prev\" aria-label=\"Rese\u00f1a anterior\" role=\"button\" tabindex=\"0\"><\/div> <\/div> <div class=\"ti-reviews-container-wrapper\">  <div data-empty=\"0\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-time=\"\" data-id=\"cfcd208495d565ef66e7dff9f98764da\" data-language=\"\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <div class=\"ti-platform-icon ti-with-tooltip\"> <span class=\"ti-tooltip\">Publicado en Google<\/span> <trustindex-image data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/icon.svg\" alt=\"Google\" width=\"20\" height=\"20\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a-\/ALV-UjUi6O8Nt8f8-R6C3EvGYNvpbOvrnYx_YKcv9QNQ5UUM0wUjZ7GP=w40-h40-c-rp-mo-br100\" alt=\"Javi Martinez profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Javi Martinez <\/div> <div class=\"ti-date\">12\/08\/2026<\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 1\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 2\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 3\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 4\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 5\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><span class=\"ti-verified-review ti-verified-platform\"><span class=\"ti-verified-tooltip\">Trustindex verifica que la fuente original de la rese\u00f1a sea Google.<\/span><\/span><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->Hola soy Javi de Pamplona me puse en contacto con esta protectora y me atendi\u00f3 Loles una chica encantadora que dio gusto poder hablar con ella ...est\u00e1bamos interesados en un cachorrito de bichon malt\u00e9s enseguida me envi\u00f3 fotos y videos de un precioso calorcito que nada mas verlo nos enamor\u00f3 hicimos todos los pasos por tel\u00e9fono y la verdad que no puedo tener ninguna queja en una semana ten\u00edamos el cacjorrito en casa nos a llegado esta ma\u00f1ana y ya estamos encantados y enamorados de el ya es parte de la familia jijiji asique much\u00edsimas gracias por todo de verdad a sido un placer el poder haber encontrados y poder disfrutar tan r\u00e1pido de el asique si est\u00e1is interesados en tener otro miembro en vuestra familia no dud\u00e9is en contactar con ell os atender\u00e1 de maravilla y tendr\u00e9is un cachorrito sano y plenas condiciones.\nMuch\u00edsimas gracias por todo<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Ocultar\" data-open-text=\"Leer m\u00e1s\"><\/span> <\/div> <\/div>  <div data-empty=\"0\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-time=\"\" data-id=\"cfcd208495d565ef66e7dff9f98764da\" data-language=\"\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <div class=\"ti-platform-icon ti-with-tooltip\"> <span class=\"ti-tooltip\">Publicado en Google<\/span> <trustindex-image data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/icon.svg\" alt=\"Google\" width=\"20\" height=\"20\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a-\/ALV-UjX5mcIkYOzeBFlGk3ykCU9RJ_krDq-qTc7OMJKPXsjaEjLfO1Iq4A=w40-h40-c-rp-mo-ba12-br100\" alt=\"Claudia Checa profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Claudia Checa <\/div> <div class=\"ti-date\">12\/08\/2026<\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 1\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 2\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 3\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 4\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 5\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><span class=\"ti-verified-review ti-verified-platform\"><span class=\"ti-verified-tooltip\">Trustindex verifica que la fuente original de la rese\u00f1a sea Google.<\/span><\/span><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->Esta es la segunda vez que compramos un cachorro en Diana de la Jara!\n\nHace 2 a\u00f1os compramos a nuestro primer cachorro Nugget y todo fue genial por lo que cuando quisimos tener otro perro pensamos en ellos y aqu\u00ed est\u00e1 Mochi ya con nosostros!\ud83e\uddf8\ud83d\udc3b\n\nLa verdad que las 2 veces que hemos interactuado con ellos han sido geniales, los perritos son preciosos y se nota que han estado bien cuidados\ud83e\udd70\n\nSiempre te resuelven las dudas y te dan muchas facilidades, nosotros somos de Gran Canaria y por tema vuelos se complic\u00f3 ir a Granada a recogerlo en las fechas que quer\u00edamos y Loles nos ofreci\u00f3 la opci\u00f3n de recogerlo en el Aeropuerto de M\u00e1laga y as\u00ed fue\ud83e\udef6\ud83c\udffb\n\nMuy contenta con el criadero y con los perritos!\ud83e\udde1\ud83e\udd0e<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Ocultar\" data-open-text=\"Leer m\u00e1s\"><\/span> <\/div> <\/div>  <div data-empty=\"0\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-time=\"\" data-id=\"cfcd208495d565ef66e7dff9f98764da\" data-language=\"\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <div class=\"ti-platform-icon ti-with-tooltip\"> <span class=\"ti-tooltip\">Publicado en Google<\/span> <trustindex-image data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/icon.svg\" alt=\"Google\" width=\"20\" height=\"20\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocJ-0jfNkoYEAC0CYkhaNOzLCFH4gGnNQkuIFt-1AYYdn_-ioQ=w40-h40-c-rp-mo-br100\" alt=\"Virginia Oca\u00f1a profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Virginia Oca\u00f1a <\/div> <div class=\"ti-date\">12\/08\/2026<\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 1\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 2\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 3\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 4\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 5\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><span class=\"ti-verified-review ti-verified-platform\"><span class=\"ti-verified-tooltip\">Trustindex verifica que la fuente original de la rese\u00f1a sea Google.<\/span><\/span><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->Yo he tenido una experiencia fant\u00e1stica. No conoc\u00edamos al criadero de nada, simplemente busc\u00e1bamos un caniche negro y dimos con Diana de la Jara, ten\u00edamos nuestras dudas porque no conoc\u00edamos a nadie que hubiera tenido experiencia con ellos, y es la mejor decisi\u00f3n que tomamos. Nos atendieron muy bien desde el primer dia, explic\u00e1ndonos desde las caracter\u00edsticas de la raza, car\u00e1cter del cachorro,como ser\u00eda de adulto, hasta tr\u00e1mites a llevar a cabo y como nos encant\u00f3 pues nos lanzamos a ello. Las instalaciones que tienen son preciosas y est\u00e1n muy cuidadas. En el caso de mi cachorro que sobre los 3 meses lo tuvimos ya en casa pues ven\u00eda con mucho trabajo hecho, era muy sociable, se dejaba cepillar, ya hac\u00eda sus necesidades en su empapador, etc.. Tambi\u00e9n me ayudaron los primeros d\u00edas en casa con las dudas que ten\u00eda y en la primera visita al veterinario le hicimos varias pruebas de salud, de par\u00e1sitos y estaba todo perfecto, en definitiva los cachorros est\u00e1n muy cuidados y ellos te atienden estupendamente antes, durante y despu\u00e9s. Estamos muy contentos.<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Ocultar\" data-open-text=\"Leer m\u00e1s\"><\/span> <\/div> <\/div>  <div data-empty=\"0\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-time=\"\" data-id=\"cfcd208495d565ef66e7dff9f98764da\" data-language=\"\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <div class=\"ti-platform-icon ti-with-tooltip\"> <span class=\"ti-tooltip\">Publicado en Google<\/span> <trustindex-image data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/icon.svg\" alt=\"Google\" width=\"20\" height=\"20\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocIFQh8WCo0hGgs4qMJ7abn8_9WirPzO14tHF9b0GkESOS8dRQ=w40-h40-c-rp-mo-br100\" alt=\"Jana Schieler profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Jana Schieler <\/div> <div class=\"ti-date\">10\/08\/2026<\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 1\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 2\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 3\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 4\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 5\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><span class=\"ti-verified-review ti-verified-platform\"><span class=\"ti-verified-tooltip\">Trustindex verifica que la fuente original de la rese\u00f1a sea Google.<\/span><\/span><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->Somos una familia alemana que ha hecho realidad el sue\u00f1o de tener un perro salchicha (teckel), y lo conseguimos gracias a Diana de la Jara. \u00bfQu\u00e9 puedo decir? Todo fue excelente, de principio a fin. Se lo recomiendo a cualquiera que quiera incorporar un nuevo miembro de cuatro patas a la familia: este es el lugar ideal. \u00a1Mil gracias por nuestra Fini, que es una preciosidad! \u00a1Hac\u00e9is un trabajo magn\u00edfico! Saludos desde Alemania, Jana.<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Ocultar\" data-open-text=\"Leer m\u00e1s\"><\/span> <\/div> <\/div>  <div data-empty=\"0\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-time=\"\" data-id=\"cfcd208495d565ef66e7dff9f98764da\" data-language=\"\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <div class=\"ti-platform-icon ti-with-tooltip\"> <span class=\"ti-tooltip\">Publicado en Google<\/span> <trustindex-image data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/icon.svg\" alt=\"Google\" width=\"20\" height=\"20\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocKdXCyGHV3IUl9gi3Qoz5iXUCf6ernotlBRcYNcTQTrFbwaoQ=w40-h40-c-rp-mo-br100\" alt=\"Jose Landi profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Jose Landi <\/div> <div class=\"ti-date\">09\/08\/2026<\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 1\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 2\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 3\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 4\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 5\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><span class=\"ti-verified-review ti-verified-platform\"><span class=\"ti-verified-tooltip\">Trustindex verifica que la fuente original de la rese\u00f1a sea Google.<\/span><\/span><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->Hola gracias por todo hac\u00e9is una gran labor con los animales por vuestra labor diaria y constancia.Por el amor hacia los animales y sus cuidados antes de la entrega,que sig\u00e1is por muchos a\u00f1os alegrando la vida de las personas con vuestras mascotas,Un fuerte abrazo desde Palma de Mallorca,Per Semper a vuestro esp\u00edritu hacia los animales<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Ocultar\" data-open-text=\"Leer m\u00e1s\"><\/span> <\/div> <\/div>  <div data-empty=\"0\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-time=\"\" data-id=\"cfcd208495d565ef66e7dff9f98764da\" data-language=\"\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <div class=\"ti-platform-icon ti-with-tooltip\"> <span class=\"ti-tooltip\">Publicado en Google<\/span> <trustindex-image data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/icon.svg\" alt=\"Google\" width=\"20\" height=\"20\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocK2_Avg0Kggip2-4Ew6LinsjNfNtFZy6NGGcDDHKxYmbMQFsA=w40-h40-c-rp-mo-br100\" alt=\"Ana Maria Teruel conesa profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Ana Maria Teruel conesa <\/div> <div class=\"ti-date\">09\/08\/2026<\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 1\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 2\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 3\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 4\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 5\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><span class=\"ti-verified-review ti-verified-platform\"><span class=\"ti-verified-tooltip\">Trustindex verifica que la fuente original de la rese\u00f1a sea Google.<\/span><\/span><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->Mi experiencia ha sido del todo satisfactoria compr\u00e9 un bich\u00f3n y vino muy sano y sin enga\u00f1os, estoy muy feliz con mi ni\u00f1o. Se llama Neo.<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Ocultar\" data-open-text=\"Leer m\u00e1s\"><\/span> <\/div> <\/div>  <div data-empty=\"0\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-time=\"\" data-id=\"cfcd208495d565ef66e7dff9f98764da\" data-language=\"\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <div class=\"ti-platform-icon ti-with-tooltip\"> <span class=\"ti-tooltip\">Publicado en Google<\/span> <trustindex-image data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/icon.svg\" alt=\"Google\" width=\"20\" height=\"20\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocKmiQWk2eZZw0viIJ_NzemBbbYC4YTyT-2BxqhYVrZl3K-xmQ=w40-h40-c-rp-mo-br100\" alt=\"Collin Mireille profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Collin Mireille <\/div> <div class=\"ti-date\">02\/08\/2026<\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 1\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 2\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 3\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 4\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 5\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><span class=\"ti-verified-review ti-verified-platform\"><span class=\"ti-verified-tooltip\">Trustindex verifica que la fuente original de la rese\u00f1a sea Google.<\/span><\/span><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->Apr\u00e8s une tres mauvaise exp\u00e9rience (grosse arnaque), je me suis tourn\u00e9e vers diana de la jara . J'ai craqu\u00e9 sur un magnifique caniche nain cr\u00e8me et un petit maltipoo caramel. Quel plaisir d'\u00e9changer avec Loles qui a su nous rassurer et mettre en place le voyage de nos petits loulous . Ils sont arriv\u00e9s aujourd'hui et nous comble d\u00e9j\u00e0 de bonheur . Merci Loles pour ta disponibilit\u00e9 et ta patience,<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Ocultar\" data-open-text=\"Leer m\u00e1s\"><\/span> <\/div> <\/div>  <div data-empty=\"0\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-time=\"\" data-id=\"cfcd208495d565ef66e7dff9f98764da\" data-language=\"\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <div class=\"ti-platform-icon ti-with-tooltip\"> <span class=\"ti-tooltip\">Publicado en Google<\/span> <trustindex-image data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/icon.svg\" alt=\"Google\" width=\"20\" height=\"20\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a-\/ALV-UjWTGGpkyIMk75FegxuSWWY-oHY2LyMeYrmEu4vEZI-8wtQOBXazhw=w40-h40-c-rp-mo-br100\" alt=\"Gazmi Ginory profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Gazmi Ginory <\/div> <div class=\"ti-date\">02\/08\/2026<\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 1\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 2\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 3\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 4\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/e.svg\" alt=\"Google star 5\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><span class=\"ti-verified-review ti-verified-platform\"><span class=\"ti-verified-tooltip\">Trustindex verifica que la fuente original de la rese\u00f1a sea Google.<\/span><\/span><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->No podr\u00edamos estar m\u00e1s contentos con nuestra experiencia. Desde el primer momento nos dieron un trato cercano y resolvieron todas nuestras dudas. Nuestra peque\u00f1a Eevee lleg\u00f3 sana, preciosa y muy bien cuidada. Se nota el cari\u00f1o y la dedicaci\u00f3n con la que cr\u00edan a sus perritos. Sin duda, recomendamos este criadero al 100 %. \u00a1Muchas gracias por todo!<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Ocultar\" data-open-text=\"Leer m\u00e1s\"><\/span> <\/div> <\/div>  <div data-empty=\"0\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-time=\"\" data-id=\"cfcd208495d565ef66e7dff9f98764da\" data-language=\"\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <div class=\"ti-platform-icon ti-with-tooltip\"> <span class=\"ti-tooltip\">Publicado en Google<\/span> <trustindex-image data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/icon.svg\" alt=\"Google\" width=\"20\" height=\"20\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocIhAME4il2IqPkFxrU5ehIZ7knRlkMZvlGhwiGQ2MX9G28plw=w40-h40-c-rp-mo-br100\" alt=\"Kathi Croft profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Kathi Croft <\/div> <div class=\"ti-date\">30\/07\/2026<\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 1\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 2\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 3\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 4\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 5\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><span class=\"ti-verified-review ti-verified-platform\"><span class=\"ti-verified-tooltip\">Trustindex verifica que la fuente original de la rese\u00f1a sea Google.<\/span><\/span><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->We had a wonderful experience with Diana de la Yara. Loles was absolutely fantastic throughout the entire process \u2013 always kind, professional, incredibly responsive, and exceptionally well organized.\n\nShe was also very flexible with the transport arrangements and did everything she could to make the process as smooth and stress-free as possible. Her communication was excellent from beginning to end, and we always felt well looked after.\n\nMost importantly, the little one arrived safely and is now very happy with his new family. We couldn't have asked for a better experience and would wholeheartedly recommend Diana de la Yara to anyone looking for a responsible and caring breeder.<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Ocultar\" data-open-text=\"Leer m\u00e1s\"><\/span> <\/div> <\/div>  <\/div> <div class=\"ti-controls-line\"> <div class=\"dot\"><\/div> <\/div>   <\/div> <\/div> <\/div> <\/template><\/pre><div data-src=\"https:\/\/cdn.trustindex.io\/loader.js?wp-widget\" data-template-id=\"trustindex-google-widget-html\" data-css-url=\"https:\/\/dianadelajara.com\/wp-content\/uploads\/trustindex-google-widget.css?1787335715\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Your ideal puppy is just a phone call away<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">For more details or to start the adoption process, simply contact us. We are here to answer any questions you may have.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Our puppies in pictures<\/h2>\n\n\n\n<div class=\"wp-block-image-gallery-block-image-gallery-block\"><div class=\"eb-parent-wrapper eb-parent-eb-image-gallery-w2ztl\"><div class=\"eb-gallery-img-wrapper eb-image-gallery-w2ztl grid overlay-bottom caption-style-0   no-isotope\" data-id=\"eb-image-gallery-w2ztl\"><a href=\"https:\/\/dianadelajara.com\/wp-content\/uploads\/2024\/11\/shih-tzu-cachorro-diana-de-la-jara-1.jpg\" rel=\"noopener\" data-fslightbox=\"gallery\" data-type=\"image\" class=\"eb-gallery-img-content eb-filter-img-\"><span class=\"eb-gallery-link-wrapper\"><img decoding=\"async\" class=\"eb-gallery-img\" src=\"https:\/\/dianadelajara.com\/wp-content\/uploads\/2024\/11\/shih-tzu-cachorro-diana-de-la-jara-1.jpg\" image-index=\"0\" alt=\"shih-tzu-puppy-diana-of-the-jara\"\/><\/span><\/a><a href=\"https:\/\/dianadelajara.com\/wp-content\/uploads\/2024\/11\/lulu-de-pomerania-cachorro-diana-de-la-jara-1.jpg\" rel=\"noopener\" data-fslightbox=\"gallery\" data-type=\"image\" class=\"eb-gallery-img-content eb-filter-img-\"><span class=\"eb-gallery-link-wrapper\"><img decoding=\"async\" class=\"eb-gallery-img\" src=\"https:\/\/dianadelajara.com\/wp-content\/uploads\/2024\/11\/lulu-de-pomerania-cachorro-diana-de-la-jara-1.jpg\" image-index=\"1\" alt=\"lulu de pomerania puppy - diana de la jara (1)\"\/><\/span><\/a><a href=\"https:\/\/dianadelajara.com\/wp-content\/uploads\/2024\/11\/caniche-toy-diana-de-la-jara.jpg\" rel=\"noopener\" data-fslightbox=\"gallery\" data-type=\"image\" class=\"eb-gallery-img-content eb-filter-img-\"><span class=\"eb-gallery-link-wrapper\"><img decoding=\"async\" class=\"eb-gallery-img\" src=\"https:\/\/dianadelajara.com\/wp-content\/uploads\/2024\/11\/caniche-toy-diana-de-la-jara.jpg\" image-index=\"2\" alt=\"poodle toy diana de la jara\"\/><\/span><\/a><a href=\"https:\/\/dianadelajara.com\/wp-content\/uploads\/2024\/11\/IMG-20241107-WA0015.jpg\" rel=\"noopener\" data-fslightbox=\"gallery\" data-type=\"image\" class=\"eb-gallery-img-content eb-filter-img-\"><span class=\"eb-gallery-link-wrapper\"><img decoding=\"async\" class=\"eb-gallery-img\" src=\"https:\/\/dianadelajara.com\/wp-content\/uploads\/2024\/11\/IMG-20241107-WA0015.jpg\" image-index=\"3\" alt=\"yorkshire terrier puppy - diana de la jara\"\/><\/span><\/a><a href=\"https:\/\/dianadelajara.com\/wp-content\/uploads\/2024\/11\/IMG-20241107-WA0014.jpg\" rel=\"noopener\" data-fslightbox=\"gallery\" data-type=\"image\" class=\"eb-gallery-img-content eb-filter-img-\"><span class=\"eb-gallery-link-wrapper\"><img decoding=\"async\" class=\"eb-gallery-img\" src=\"https:\/\/dianadelajara.com\/wp-content\/uploads\/2024\/11\/IMG-20241107-WA0014.jpg\" image-index=\"4\" alt=\"Labrador - Diana de la Jara\"\/><\/span><\/a><a href=\"https:\/\/dianadelajara.com\/wp-content\/uploads\/2024\/11\/lulu-de-pomerania-cachorro-diana-de-la-jara-2.jpg\" rel=\"noopener\" data-fslightbox=\"gallery\" data-type=\"image\" class=\"eb-gallery-img-content eb-filter-img-\"><span class=\"eb-gallery-link-wrapper\"><img decoding=\"async\" class=\"eb-gallery-img\" src=\"https:\/\/dianadelajara.com\/wp-content\/uploads\/2024\/11\/lulu-de-pomerania-cachorro-diana-de-la-jara-2.jpg\" image-index=\"5\" alt=\"\"\/><\/span><\/a><a href=\"https:\/\/dianadelajara.com\/wp-content\/uploads\/2024\/11\/caniche-toy-cachorro-diana-de-la-jara-2.jpg\" rel=\"noopener\" data-fslightbox=\"gallery\" data-type=\"image\" class=\"eb-gallery-img-content eb-filter-img-\"><span class=\"eb-gallery-link-wrapper\"><img decoding=\"async\" class=\"eb-gallery-img\" src=\"https:\/\/dianadelajara.com\/wp-content\/uploads\/2024\/11\/caniche-toy-cachorro-diana-de-la-jara-2.jpg\" image-index=\"6\" alt=\"poodle toy puppy - diana de la jara (2)\"\/><\/span><\/a><a href=\"https:\/\/dianadelajara.com\/wp-content\/uploads\/2024\/11\/bichon-maltes-cachorro-diana-de-la-jara-2.jpg\" rel=\"noopener\" data-fslightbox=\"gallery\" data-type=\"image\" class=\"eb-gallery-img-content eb-filter-img-\"><span class=\"eb-gallery-link-wrapper\"><img decoding=\"async\" class=\"eb-gallery-img\" src=\"https:\/\/dianadelajara.com\/wp-content\/uploads\/2024\/11\/bichon-maltes-cachorro-diana-de-la-jara-2.jpg\" image-index=\"7\" alt=\"\"\/><\/span><\/a><a href=\"https:\/\/dianadelajara.com\/wp-content\/uploads\/2024\/11\/caniche-toy-diana-de-la-jara-4.jpg\" rel=\"noopener\" data-fslightbox=\"gallery\" data-type=\"image\" class=\"eb-gallery-img-content eb-filter-img-\"><span class=\"eb-gallery-link-wrapper\"><img decoding=\"async\" class=\"eb-gallery-img\" src=\"https:\/\/dianadelajara.com\/wp-content\/uploads\/2024\/11\/caniche-toy-diana-de-la-jara-4.jpg\" image-index=\"8\" alt=\"\"\/><\/span><\/a><a href=\"https:\/\/dianadelajara.com\/wp-content\/uploads\/2024\/11\/beagle-cachorro-diana-de-la-jara-2.jpg\" rel=\"noopener\" data-fslightbox=\"gallery\" data-type=\"image\" class=\"eb-gallery-img-content eb-filter-img-\"><span class=\"eb-gallery-link-wrapper\"><img decoding=\"async\" class=\"eb-gallery-img\" src=\"https:\/\/dianadelajara.com\/wp-content\/uploads\/2024\/11\/beagle-cachorro-diana-de-la-jara-2.jpg\" image-index=\"9\" alt=\"beagle puppy diana de la jara (2)\"\/><\/span><\/a><a href=\"https:\/\/dianadelajara.com\/wp-content\/uploads\/2024\/11\/maltipoo-cachorro-diana-de-la-jara-2.jpg\" rel=\"noopener\" data-fslightbox=\"gallery\" data-type=\"image\" class=\"eb-gallery-img-content eb-filter-img-\"><span class=\"eb-gallery-link-wrapper\"><img decoding=\"async\" class=\"eb-gallery-img\" src=\"https:\/\/dianadelajara.com\/wp-content\/uploads\/2024\/11\/maltipoo-cachorro-diana-de-la-jara-2.jpg\" image-index=\"10\" alt=\"maltipoo puppy - diana de la jara 2\"\/><\/span><\/a><a href=\"https:\/\/dianadelajara.com\/wp-content\/uploads\/2024\/11\/beagle-cachorro-diana-de-la-jara-3.jpg\" rel=\"noopener\" data-fslightbox=\"gallery\" data-type=\"image\" class=\"eb-gallery-img-content eb-filter-img-\"><span class=\"eb-gallery-link-wrapper\"><img decoding=\"async\" class=\"eb-gallery-img\" src=\"https:\/\/dianadelajara.com\/wp-content\/uploads\/2024\/11\/beagle-cachorro-diana-de-la-jara-3.jpg\" image-index=\"11\" alt=\"\"\/><\/span><\/a><a href=\"https:\/\/dianadelajara.com\/wp-content\/uploads\/2024\/11\/bulldog-frances-cachorro-diana-de-la-jara-2.jpg\" rel=\"noopener\" data-fslightbox=\"gallery\" data-type=\"image\" class=\"eb-gallery-img-content eb-filter-img-\"><span class=\"eb-gallery-link-wrapper\"><img decoding=\"async\" class=\"eb-gallery-img\" src=\"https:\/\/dianadelajara.com\/wp-content\/uploads\/2024\/11\/bulldog-frances-cachorro-diana-de-la-jara-2.jpg\" image-index=\"12\" alt=\"\"\/><\/span><\/a><a href=\"https:\/\/dianadelajara.com\/wp-content\/uploads\/2024\/11\/caniche-toy-cachorro-diana-de-la-jara-1.jpg\" rel=\"noopener\" data-fslightbox=\"gallery\" data-type=\"image\" class=\"eb-gallery-img-content eb-filter-img-\"><span class=\"eb-gallery-link-wrapper\"><img decoding=\"async\" class=\"eb-gallery-img\" src=\"https:\/\/dianadelajara.com\/wp-content\/uploads\/2024\/11\/caniche-toy-cachorro-diana-de-la-jara-1.jpg\" image-index=\"13\" alt=\"\"\/><\/span><\/a><a href=\"https:\/\/dianadelajara.com\/wp-content\/uploads\/2024\/11\/bichon-maltes-cachorro-diana-de-la-jara-1.jpg\" rel=\"noopener\" data-fslightbox=\"gallery\" data-type=\"image\" class=\"eb-gallery-img-content eb-filter-img-\"><span class=\"eb-gallery-link-wrapper\"><img decoding=\"async\" class=\"eb-gallery-img\" src=\"https:\/\/dianadelajara.com\/wp-content\/uploads\/2024\/11\/bichon-maltes-cachorro-diana-de-la-jara-1.jpg\" image-index=\"14\" alt=\"\"\/><\/span><\/a><a href=\"https:\/\/dianadelajara.com\/wp-content\/uploads\/2024\/11\/maltipoos-negro-e1730920535987.jpg\" rel=\"noopener\" data-fslightbox=\"gallery\" data-type=\"image\" class=\"eb-gallery-img-content eb-filter-img-\"><span class=\"eb-gallery-link-wrapper\"><img decoding=\"async\" class=\"eb-gallery-img\" src=\"https:\/\/dianadelajara.com\/wp-content\/uploads\/2024\/11\/maltipoos-negro-e1730920535987.jpg\" image-index=\"15\" alt=\"maltipoos black\"\/><\/span><\/a><a href=\"https:\/\/dianadelajara.com\/wp-content\/uploads\/2024\/11\/yorkshire-cachorritos.jpg\" rel=\"noopener\" data-fslightbox=\"gallery\" data-type=\"image\" class=\"eb-gallery-img-content eb-filter-img-\"><span class=\"eb-gallery-link-wrapper\"><img decoding=\"async\" class=\"eb-gallery-img\" src=\"https:\/\/dianadelajara.com\/wp-content\/uploads\/2024\/11\/yorkshire-cachorritos.jpg\" image-index=\"16\" alt=\"yorkshire puppies\"\/><\/span><\/a><a href=\"https:\/\/dianadelajara.com\/wp-content\/uploads\/2024\/11\/yorkshire.jpg\" rel=\"noopener\" data-fslightbox=\"gallery\" data-type=\"image\" class=\"eb-gallery-img-content eb-filter-img-\"><span class=\"eb-gallery-link-wrapper\"><img decoding=\"async\" class=\"eb-gallery-img\" src=\"https:\/\/dianadelajara.com\/wp-content\/uploads\/2024\/11\/yorkshire.jpg\" image-index=\"17\" alt=\"\"\/><\/span><\/a><a href=\"https:\/\/dianadelajara.com\/wp-content\/uploads\/2024\/11\/westy-thor2.jpg\" rel=\"noopener\" data-fslightbox=\"gallery\" data-type=\"image\" class=\"eb-gallery-img-content eb-filter-img-\"><span class=\"eb-gallery-link-wrapper\"><img decoding=\"async\" class=\"eb-gallery-img\" src=\"https:\/\/dianadelajara.com\/wp-content\/uploads\/2024\/11\/westy-thor2.jpg\" image-index=\"18\" alt=\"\"\/><\/span><\/a><a href=\"https:\/\/dianadelajara.com\/wp-content\/uploads\/2024\/11\/shih-tzu-e1730918413721.jpg\" rel=\"noopener\" data-fslightbox=\"gallery\" data-type=\"image\" class=\"eb-gallery-img-content eb-filter-img-\"><span class=\"eb-gallery-link-wrapper\"><img decoding=\"async\" class=\"eb-gallery-img\" src=\"https:\/\/dianadelajara.com\/wp-content\/uploads\/2024\/11\/shih-tzu-e1730918413721.jpg\" image-index=\"19\" alt=\"shih tzu\"\/><\/span><\/a><a href=\"https:\/\/dianadelajara.com\/wp-content\/uploads\/2024\/11\/nala-bichon-maltes.jpg\" rel=\"noopener\" data-fslightbox=\"gallery\" data-type=\"image\" class=\"eb-gallery-img-content eb-filter-img-\"><span class=\"eb-gallery-link-wrapper\"><img decoding=\"async\" class=\"eb-gallery-img\" src=\"https:\/\/dianadelajara.com\/wp-content\/uploads\/2024\/11\/nala-bichon-maltes.jpg\" image-index=\"20\" alt=\"\"\/><\/span><\/a><a href=\"https:\/\/dianadelajara.com\/wp-content\/uploads\/2024\/11\/caniche-apricor-laica.jpg\" rel=\"noopener\" data-fslightbox=\"gallery\" data-type=\"image\" class=\"eb-gallery-img-content eb-filter-img-\"><span class=\"eb-gallery-link-wrapper\"><img decoding=\"async\" class=\"eb-gallery-img\" src=\"https:\/\/dianadelajara.com\/wp-content\/uploads\/2024\/11\/caniche-apricor-laica.jpg\" image-index=\"21\" alt=\"\"\/><\/span><\/a><a href=\"https:\/\/dianadelajara.com\/wp-content\/uploads\/2024\/11\/caniche-toy-blanco.jpg\" rel=\"noopener\" data-fslightbox=\"gallery\" data-type=\"image\" class=\"eb-gallery-img-content eb-filter-img-\"><span class=\"eb-gallery-link-wrapper\"><img decoding=\"async\" class=\"eb-gallery-img\" src=\"https:\/\/dianadelajara.com\/wp-content\/uploads\/2024\/11\/caniche-toy-blanco.jpg\" image-index=\"22\" alt=\"\"\/><\/span><\/a><a href=\"https:\/\/dianadelajara.com\/wp-content\/uploads\/2024\/11\/pomerania-puppies-e1730917198673.jpg\" rel=\"noopener\" data-fslightbox=\"gallery\" data-type=\"image\" class=\"eb-gallery-img-content eb-filter-img-\"><span class=\"eb-gallery-link-wrapper\"><img decoding=\"async\" class=\"eb-gallery-img\" src=\"https:\/\/dianadelajara.com\/wp-content\/uploads\/2024\/11\/pomerania-puppies-e1730917198673.jpg\" image-index=\"23\" alt=\"pomeranian puppies\"\/><\/span><\/a><a href=\"https:\/\/dianadelajara.com\/wp-content\/uploads\/2024\/11\/pomerania-lobo.jpg\" rel=\"noopener\" data-fslightbox=\"gallery\" data-type=\"image\" class=\"eb-gallery-img-content eb-filter-img-\"><span class=\"eb-gallery-link-wrapper\"><img decoding=\"async\" class=\"eb-gallery-img\" src=\"https:\/\/dianadelajara.com\/wp-content\/uploads\/2024\/11\/pomerania-lobo.jpg\" image-index=\"24\" alt=\"\"\/><\/span><\/a><a href=\"https:\/\/dianadelajara.com\/wp-content\/uploads\/2024\/10\/chihuahua-diana-de-la-jara2.jpg\" rel=\"noopener\" data-fslightbox=\"gallery\" data-type=\"image\" class=\"eb-gallery-img-content eb-filter-img-\"><span class=\"eb-gallery-link-wrapper\"><img decoding=\"async\" class=\"eb-gallery-img\" src=\"https:\/\/dianadelajara.com\/wp-content\/uploads\/2024\/10\/chihuahua-diana-de-la-jara2.jpg\" image-index=\"25\" alt=\"chihuahua diana de la jara\"\/><\/span><\/a><a href=\"https:\/\/dianadelajara.com\/wp-content\/uploads\/2024\/11\/pomerania-puppy.jpg\" rel=\"noopener\" data-fslightbox=\"gallery\" data-type=\"image\" class=\"eb-gallery-img-content eb-filter-img-\"><span class=\"eb-gallery-link-wrapper\"><img decoding=\"async\" class=\"eb-gallery-img\" src=\"https:\/\/dianadelajara.com\/wp-content\/uploads\/2024\/11\/pomerania-puppy.jpg\" image-index=\"26\" alt=\"\"\/><\/span><\/a><a href=\"https:\/\/dianadelajara.com\/wp-content\/uploads\/2024\/11\/pomerania-toy.jpg\" rel=\"noopener\" data-fslightbox=\"gallery\" data-type=\"image\" class=\"eb-gallery-img-content eb-filter-img-\"><span class=\"eb-gallery-link-wrapper\"><img decoding=\"async\" class=\"eb-gallery-img\" src=\"https:\/\/dianadelajara.com\/wp-content\/uploads\/2024\/11\/pomerania-toy.jpg\" image-index=\"27\" alt=\"\"\/><\/span><\/a><a href=\"https:\/\/dianadelajara.com\/wp-content\/uploads\/2024\/11\/bichon-maltes-bimba.jpg\" rel=\"noopener\" data-fslightbox=\"gallery\" data-type=\"image\" class=\"eb-gallery-img-content eb-filter-img-\"><span class=\"eb-gallery-link-wrapper\"><img decoding=\"async\" class=\"eb-gallery-img\" src=\"https:\/\/dianadelajara.com\/wp-content\/uploads\/2024\/11\/bichon-maltes-bimba.jpg\" image-index=\"28\" alt=\"\"\/><\/span><\/a><a href=\"https:\/\/dianadelajara.com\/wp-content\/uploads\/2024\/11\/bichon-maltes.jpg\" rel=\"noopener\" data-fslightbox=\"gallery\" data-type=\"image\" class=\"eb-gallery-img-content eb-filter-img-\"><span class=\"eb-gallery-link-wrapper\"><img decoding=\"async\" class=\"eb-gallery-img\" src=\"https:\/\/dianadelajara.com\/wp-content\/uploads\/2024\/11\/bichon-maltes.jpg\" image-index=\"29\" alt=\"bichon maltese\"\/><\/span><\/a><a href=\"https:\/\/dianadelajara.com\/wp-content\/uploads\/2024\/10\/chihuahua-diana-de-la-jara.jpg\" rel=\"noopener\" data-fslightbox=\"gallery\" data-type=\"image\" class=\"eb-gallery-img-content eb-filter-img-\"><span class=\"eb-gallery-link-wrapper\"><img decoding=\"async\" class=\"eb-gallery-img\" src=\"https:\/\/dianadelajara.com\/wp-content\/uploads\/2024\/10\/chihuahua-diana-de-la-jara.jpg\" image-index=\"30\" alt=\"chihuahua diana de la jara\"\/><\/span><\/a><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Dog kennel in Sant Boi de Llobregat with a zoological nucleus and 30 years of experience. We work with all breeds and our puppies undergo veterinary checks.<\/p>","protected":false},"author":1,"featured_media":5112,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_eb_attr":"","Raza":"","Precio":"","Sexo":"","Color":"","Tama\u00f1o":"","Fecha_Nacimiento":"","Entrega_Edad":"","ID_Nocodb":"","footnotes":""},"categories":[352],"tags":[129],"class_list":["post-5111","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ciudad","tag-sant-boi-de-llobregat","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-33"],"_links":{"self":[{"href":"https:\/\/dianadelajara.com\/en\/wp-json\/wp\/v2\/posts\/5111","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dianadelajara.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dianadelajara.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dianadelajara.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dianadelajara.com\/en\/wp-json\/wp\/v2\/comments?post=5111"}],"version-history":[{"count":0,"href":"https:\/\/dianadelajara.com\/en\/wp-json\/wp\/v2\/posts\/5111\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dianadelajara.com\/en\/wp-json\/wp\/v2\/media\/5112"}],"wp:attachment":[{"href":"https:\/\/dianadelajara.com\/en\/wp-json\/wp\/v2\/media?parent=5111"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dianadelajara.com\/en\/wp-json\/wp\/v2\/categories?post=5111"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dianadelajara.com\/en\/wp-json\/wp\/v2\/tags?post=5111"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}